{"id":2657,"date":"2019-10-09T17:32:31","date_gmt":"2019-10-09T20:32:31","guid":{"rendered":"http:\/\/emaklabin.org.br\/explore\/obras\/cadeira-dobravel-2\/"},"modified":"2019-10-09T17:32:31","modified_gmt":"2019-10-09T20:32:31","slug":"cadeira-dobravel-2","status":"publish","type":"obras","link":"https:\/\/emaklabin.org.br\/explore\/obras\/cadeira-dobravel-2\/","title":{"rendered":"Cadeira dobr\u00e1vel"},"author":1,"featured_media":2658,"comment_status":"open","ping_status":"closed","template":"","class_list":["post-2657","obras","type-obras","status-publish","has-post-thumbnail","hentry","obra_az-c","classificacao-objetos-domesticos-mobiliario","nucleo-mobiliario-europeu","ambiente-quarto-principal"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cadeira dobr\u00e1vel - Explore<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/emaklabin.org.br\/explore\/obras\/cadeira-dobravel-2\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cadeira dobr\u00e1vel - Explore\" \/>\n<meta property=\"og:url\" content=\"https:\/\/emaklabin.org.br\/explore\/obras\/cadeira-dobravel-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Explore\" \/>\n<meta property=\"og:image\" content=\"https:\/\/emaklabin.org.br\/explore\/wp-content\/uploads\/M0379.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"421\" \/>\n\t<meta property=\"og:image:height\" content=\"613\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/emaklabin.org.br\\\/explore\\\/obras\\\/cadeira-dobravel-2\\\/\",\"url\":\"https:\\\/\\\/emaklabin.org.br\\\/explore\\\/obras\\\/cadeira-dobravel-2\\\/\",\"name\":\"Cadeira dobr\u00e1vel - Explore\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/emaklabin.org.br\\\/explore\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/emaklabin.org.br\\\/explore\\\/obras\\\/cadeira-dobravel-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/emaklabin.org.br\\\/explore\\\/obras\\\/cadeira-dobravel-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/emaklabin.org.br\\\/explore\\\/wp-content\\\/uploads\\\/M0379.jpg\",\"datePublished\":\"2019-10-09T20:32:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/emaklabin.org.br\\\/explore\\\/obras\\\/cadeira-dobravel-2\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/emaklabin.org.br\\\/explore\\\/obras\\\/cadeira-dobravel-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/emaklabin.org.br\\\/explore\\\/obras\\\/cadeira-dobravel-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/emaklabin.org.br\\\/explore\\\/wp-content\\\/uploads\\\/M0379.jpg\",\"contentUrl\":\"https:\\\/\\\/emaklabin.org.br\\\/explore\\\/wp-content\\\/uploads\\\/M0379.jpg\",\"width\":421,\"height\":613},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/emaklabin.org.br\\\/explore\\\/obras\\\/cadeira-dobravel-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/emaklabin.org.br\\\/explore\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Obras\",\"item\":\"https:\\\/\\\/emaklabin.org.br\\\/explore\\\/obras\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Cadeira dobr\u00e1vel\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/emaklabin.org.br\\\/explore\\\/#website\",\"url\":\"https:\\\/\\\/emaklabin.org.br\\\/explore\\\/\",\"name\":\"Explore! Funda\u00e7\u00e3o Ema Klabin\",\"description\":\"Descubra a Cole\u00e7\u00e3o Ema Klabin\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/emaklabin.org.br\\\/explore\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cadeira dobr\u00e1vel - Explore","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/emaklabin.org.br\/explore\/obras\/cadeira-dobravel-2\/","og_locale":"pt_BR","og_type":"article","og_title":"Cadeira dobr\u00e1vel - Explore","og_url":"https:\/\/emaklabin.org.br\/explore\/obras\/cadeira-dobravel-2\/","og_site_name":"Explore","og_image":[{"width":421,"height":613,"url":"https:\/\/emaklabin.org.br\/explore\/wp-content\/uploads\/M0379.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/emaklabin.org.br\/explore\/obras\/cadeira-dobravel-2\/","url":"https:\/\/emaklabin.org.br\/explore\/obras\/cadeira-dobravel-2\/","name":"Cadeira dobr\u00e1vel - Explore","isPartOf":{"@id":"https:\/\/emaklabin.org.br\/explore\/#website"},"primaryImageOfPage":{"@id":"https:\/\/emaklabin.org.br\/explore\/obras\/cadeira-dobravel-2\/#primaryimage"},"image":{"@id":"https:\/\/emaklabin.org.br\/explore\/obras\/cadeira-dobravel-2\/#primaryimage"},"thumbnailUrl":"https:\/\/emaklabin.org.br\/explore\/wp-content\/uploads\/M0379.jpg","datePublished":"2019-10-09T20:32:31+00:00","breadcrumb":{"@id":"https:\/\/emaklabin.org.br\/explore\/obras\/cadeira-dobravel-2\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/emaklabin.org.br\/explore\/obras\/cadeira-dobravel-2\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/emaklabin.org.br\/explore\/obras\/cadeira-dobravel-2\/#primaryimage","url":"https:\/\/emaklabin.org.br\/explore\/wp-content\/uploads\/M0379.jpg","contentUrl":"https:\/\/emaklabin.org.br\/explore\/wp-content\/uploads\/M0379.jpg","width":421,"height":613},{"@type":"BreadcrumbList","@id":"https:\/\/emaklabin.org.br\/explore\/obras\/cadeira-dobravel-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/emaklabin.org.br\/explore\/"},{"@type":"ListItem","position":2,"name":"Obras","item":"https:\/\/emaklabin.org.br\/explore\/obras\/"},{"@type":"ListItem","position":3,"name":"Cadeira dobr\u00e1vel"}]},{"@type":"WebSite","@id":"https:\/\/emaklabin.org.br\/explore\/#website","url":"https:\/\/emaklabin.org.br\/explore\/","name":"Explore! Funda\u00e7\u00e3o Ema Klabin","description":"Descubra a Cole\u00e7\u00e3o Ema Klabin","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/emaklabin.org.br\/explore\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"}]}},"meta_box":{"obra-metabox_referencias":[],"obra-metabox_externo":[],"obra-metabox_exposicoes":[],"obras_to_autores_to":["1578"],"obra_em_destaque_from":[]},"_links":{"self":[{"href":"https:\/\/emaklabin.org.br\/explore\/wp-json\/wp\/v2\/obras\/2657","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/emaklabin.org.br\/explore\/wp-json\/wp\/v2\/obras"}],"about":[{"href":"https:\/\/emaklabin.org.br\/explore\/wp-json\/wp\/v2\/types\/obras"}],"author":[{"embeddable":true,"href":"https:\/\/emaklabin.org.br\/explore\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/emaklabin.org.br\/explore\/wp-json\/wp\/v2\/comments?post=2657"}],"version-history":[{"count":0,"href":"https:\/\/emaklabin.org.br\/explore\/wp-json\/wp\/v2\/obras\/2657\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/emaklabin.org.br\/explore\/wp-json\/wp\/v2\/media\/2658"}],"wp:attachment":[{"href":"https:\/\/emaklabin.org.br\/explore\/wp-json\/wp\/v2\/media?parent=2657"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}